{"id":40109,"date":"2021-01-14T03:06:13","date_gmt":"2021-01-14T02:06:13","guid":{"rendered":"https:\/\/www.creads.com\/projets-design-graphisme\/"},"modified":"2021-07-13T14:36:39","modified_gmt":"2021-07-13T12:36:39","slug":"proyecto-diseno","status":"publish","type":"page","link":"https:\/\/www.creads.com\/es\/proyecto-diseno\/","title":{"rendered":"Nuestros clientes"},"content":{"rendered":"<section class=\"creads-block creads-list-creations\" style=\"background-color:#ffffff;\">\n  <div class=\"container\">\n    <h1 class=\"title-medium\">\u00bfQUIERES VER EL RESULTADO?<\/h1><p class=\"intro\">Aqu\u00ed te mostramos algunos de nuestros trabajos. <br \/>\r\nYa lo sabemos, \u00a1dan ganas!<\/p>    <div class=\"filters-container\">\n      <span class=\"filters-label\">Filtrar nuestros trabajos por:<\/span>\n      <div class=\"select-container\">\n        <select class=\"filter-brand default\">\n          <option value=\"\" selected hidden>Marca<\/option>\n          <option value=\"*\">All our selection<\/option>\n          <option value=\"737\">ACTISS<\/option><option value=\"738\">AGRICULTURES ET TERRITOIRES<\/option><option value=\"739\">AIRBUS<\/option><option value=\"742\">ALGO<\/option><option value=\"743\">ALIX<\/option><option value=\"746\">AMERICAN EXPRESS<\/option><option value=\"751\">ASTREES<\/option><option value=\"752\">ATELIER D\u2019AMAYA<\/option><option value=\"753\">AUDIKA<\/option><option value=\"754\">AUMAX<\/option><option value=\"755\">AUTODISTRIBUTION<\/option><option value=\"756\">BASS ME<\/option><option value=\"757\">BBRAUN MEDICAL<\/option><option value=\"758\">BEEKAST<\/option><option value=\"760\">BIGMAT<\/option><option value=\"761\">BOND INTERNATIONAL<\/option><option value=\"762\">BOULANGER<\/option><option value=\"763\">BOURSORAMA<\/option><option value=\"765\">BURGER KING<\/option><option value=\"766\">CAISSE D&#8217;EPARGNE<\/option><option value=\"767\">CARAPASS<\/option><option value=\"769\">CAUDALIE<\/option><option value=\"770\">CHRONOPOST<\/option><option value=\"771\">CITRO\u00cbN<\/option><option value=\"1242\">COCA-COLA<\/option><option value=\"772\">COFIDIS<\/option><option value=\"773\">COLISSIMO<\/option><option value=\"776\">COOPENGO<\/option><option value=\"777\">COVEA<\/option><option value=\"779\">DAILYMOTION<\/option><option value=\"780\">DANAO<\/option><option value=\"781\">DANONE<\/option><option value=\"782\">DASH<\/option><option value=\"783\">DBA<\/option><option value=\"784\">DERMANCE<\/option><option value=\"785\">DEYS<\/option><option value=\"786\">DIABOLOCOM<\/option><option value=\"1239\">Direct Assurance<\/option><option value=\"789\">DRIVY<\/option><option value=\"790\">EASY2GO<\/option><option value=\"791\">EBAY<\/option><option value=\"792\">EBIOS<\/option><option value=\"793\">EDC<\/option><option value=\"796\">ELIOS<\/option><option value=\"797\">ELRES<\/option><option value=\"799\">ENGIE<\/option><option value=\"803\">EVANEOS<\/option><option value=\"804\">EVIAN<\/option><option value=\"805\">FAUCHON<\/option><option value=\"807\">FERRERO<\/option><option value=\"808\">FINAWAY COURTAGE<\/option><option value=\"809\">FLUIGENT<\/option><option value=\"810\">FNAC DARTY<\/option><option value=\"811\">FRENCH CUISINE<\/option><option value=\"814\">GENERIA<\/option><option value=\"815\">GENERIK Paris<\/option><option value=\"816\">GRAIN DE SAIL<\/option><option value=\"818\">GRDF<\/option><option value=\"819\">GREEN ALTERNATIVE<\/option><option value=\"820\">GROUPE MACIF<\/option><option value=\"821\">GROUPE SNCF<\/option><option value=\"822\">GROUPE SOLVAY<\/option><option value=\"823\">HELLOFRESH<\/option><option value=\"827\">IGNITION PROGRAM<\/option><option value=\"828\">INDIGO<\/option><option value=\"829\">INTERCLOUD<\/option><option value=\"830\">INVIVO<\/option><option value=\"834\">JLL<\/option><option value=\"837\">KOZIKAZA<\/option><option value=\"841\">LA POSTE<\/option><option value=\"842\">LAB<\/option><option value=\"844\">LAVINIA<\/option><option value=\"847\">LEADER PRICE<\/option><option value=\"849\">LEETCHI<\/option><option value=\"850\">LELYNX.FR<\/option><option value=\"851\">LEON DE BRUXELLES<\/option><option value=\"852\">LEONIE&#8217;S<\/option><option value=\"855\">LES TROIS PETITS GOURMANDS<\/option><option value=\"856\">LIMONETIK<\/option><option value=\"858\">MACSF ASSURANCES<\/option><option value=\"859\">MAGGI<\/option><option value=\"860\">MAMA ROASTA<\/option><option value=\"861\">MANGO<\/option><option value=\"862\">MANOMANO<\/option><option value=\"867\">MES PETITES FOLIES<\/option><option value=\"869\">MMA<\/option><option value=\"871\">MUSEVA<\/option><option value=\"872\">MY BIG BANG<\/option><option value=\"873\">MYDIEU<\/option><option value=\"874\">NEEDHELP<\/option><option value=\"877\">OH YES<\/option><option value=\"879\">OPEN TOUR<\/option><option value=\"881\">OSCARO<\/option><option value=\"882\">OUIBUS<\/option><option value=\"883\">PETIT BATEAU<\/option><option value=\"884\">PILOT<\/option><option value=\"886\">PIZZA HUT<\/option><option value=\"887\">PONANT<\/option><option value=\"888\">RENAULT<\/option><option value=\"889\">RETAILMENOT<\/option><option value=\"890\">ROLAND GARROS<\/option><option value=\"891\">ROUJE<\/option><option value=\"892\">SEAGOOD<\/option><option value=\"899\">SUNNY DELIGHT<\/option><option value=\"900\">SUP DE LUXE<\/option><option value=\"901\">SWAF<\/option><option value=\"902\">TAIKI<\/option><option value=\"903\">TCL<\/option><option value=\"733\">TIFAKI HAZI<\/option><option value=\"906\">URGO<\/option><option value=\"907\">VETOQUINOL<\/option><option value=\"909\">WEFINUP<\/option><option value=\"911\">WISEED<\/option><option value=\"912\">WITHINGS<\/option><option value=\"913\">YVES ROCHER<\/option>        <\/select>\n        <div class=\"arrow\"><\/div>\n      <\/div>\n      <div class=\"select-container\">\n        <select class=\"filter-sector default\">\n          <option value=\"\" selected hidden>Sector<\/option>\n          <option value=\"*\">All our selection<\/option>\n          <option value=\"916\">Agroalimentaci\u00f3n<\/option><option value=\"918\">Asociaciones<\/option><option value=\"919\">Automoci\u00f3n \/ Log\u00edstica \/ Transporte<\/option><option value=\"920\">Bancos \/ Seguros \/ Servicios financieros<\/option><option value=\"921\">Belleza \/ Perfumer\u00eda<\/option><option value=\"923\">Comercio minorista \/ Gran distribuci\u00f3n<\/option><option value=\"924\">Comunicaci\u00f3n \/ Marketing \/ Informaci\u00f3n<\/option><option value=\"926\">Cultura \/ Deportes \/ Ocio<\/option><option value=\"929\">Educaci\u00f3n \/ Formaci\u00f3n<\/option><option value=\"927\">Energ\u00eda<\/option><option value=\"932\">Fabricaci\u00f3n \/ Venta al por mayor<\/option><option value=\"934\">Hotel \/ Restaurante \/ Turismo<\/option><option value=\"936\">Industria textil \/ Joyer\u00eda<\/option><option value=\"941\">M\u00e9dico \/ Farmac\u00e9utico<\/option><option value=\"922\">Productos qu\u00edmicos \/ Pl\u00e1sticos \/ Envases<\/option><option value=\"734\">Servicios a particulares \/ Comunidades \/ Empresas<\/option>        <\/select>\n        <div class=\"arrow\"><\/div>\n      <\/div>\n      <div class=\"select-container\">\n        <select class=\"filter-offering default\">\n          <option value=\"\" selected hidden>Servicio<\/option>\n          <option value=\"*\">All our selection<\/option>\n          <option value=\"946\">A medida<\/option><option value=\"735\">Animaci\u00f3n del logotipo<\/option><option value=\"967\">Banners web<\/option><option value=\"947\">Carta de deseos<\/option><option value=\"952\">Cartel<\/option><option value=\"954\">Flyer<\/option><option value=\"950\">Folleto \/ Cat\u00e1logo<\/option><option value=\"958\">Identidad visual<\/option><option value=\"945\">Ilustraci\u00f3n \/ Visual<\/option><option value=\"955\">Infograf\u00eda<\/option><option value=\"956\">Kak\u00e9mono<\/option><option value=\"951\">Logo<\/option><option value=\"957\">Mascota<\/option><option value=\"948\">Motion Design<\/option><option value=\"964\">Newsletters<\/option><option value=\"965\">Nombre de la marca \/ Naming<\/option><option value=\"959\">Packaging<\/option><option value=\"966\">Powerpoint<\/option><option value=\"949\">Redes sociales<\/option><option value=\"953\">Rodaje y montaje<\/option><option value=\"960\">Stand<\/option><option value=\"961\">UI Design<\/option><option value=\"962\">UX Design<\/option><option value=\"736\">V\u00eddeo<\/option><option value=\"968\">Video Charter \/ Dise\u00f1o<\/option><option value=\"963\">WordPress<\/option>        <\/select>\n        <div class=\"arrow\"><\/div>\n      <\/div>\n    <\/div>\n    <div class=\"creations-container\" data-creations-per-page=\"9\"><\/div>\n    <div class=\"pagination-container\"><\/div>\n  <\/div>\n  <div id=\"creation-video-57384\" class=\"creads-video-frame mfp-hide creads-video-creation-57392\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/08\/CREADS-avec-GENERIK-Paris-BB-Hair-Styling.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54572\" class=\"creads-video-frame mfp-hide creads-video-creation-55954\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/Coca-cola-intro-1.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54577\" class=\"creads-video-frame mfp-hide creads-video-creation-55954\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/COCA-COLA_maxwidth2-v1.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54543\" class=\"creads-video-frame mfp-hide creads-video-creation-55948\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/Gastronomy_AMEX-v4.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54551\" class=\"creads-video-frame mfp-hide creads-video-creation-55948\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/Conciergerie_AMEX-v2-1.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54539\" class=\"creads-video-frame mfp-hide creads-video-creation-55948\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/Assurance_AMEX-v2.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54547\" class=\"creads-video-frame mfp-hide creads-video-creation-55948\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/Welcome-Offer_AMEX-v4.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54561\" class=\"creads-video-frame mfp-hide creads-video-creation-55942\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/Amex-Intro.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54524\" class=\"creads-video-frame mfp-hide creads-video-creation-55942\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/AMEX-Depenses-au-Quotidien_v7-1.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54512\" class=\"creads-video-frame mfp-hide creads-video-creation-55942\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/AMEX-Assurance-Voyage_v4.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54520\" class=\"creads-video-frame mfp-hide creads-video-creation-55942\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/AMEX-Value-for-Money_v7.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-54611\" class=\"creads-video-frame mfp-hide creads-video-creation-55931\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/07\/Direct-Assurance-intro.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2033\" class=\"creads-video-frame mfp-hide creads-video-creation-47169\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/video-sncf-motiondesign.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-4341\" class=\"creads-video-frame mfp-hide creads-video-creation-47164\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/03\/Spot-Generik.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1455\" class=\"creads-video-frame mfp-hide creads-video-creation-47143\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Pins_Anime_Kinder_01.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1457\" class=\"creads-video-frame mfp-hide creads-video-creation-47143\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Pins_Anime_Kinder_02.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2015\" class=\"creads-video-frame mfp-hide creads-video-creation-47127\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/PILOT-PINTOR-MUSIQUE.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2013\" class=\"creads-video-frame mfp-hide creads-video-creation-47127\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/PILOT-PINTOR-Gourde-personnalisable.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1875\" class=\"creads-video-frame mfp-hide creads-video-creation-47114\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Exemple-de-vide\u0301o-dentreprise-avec-interview-Leetchi-1.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1877\" class=\"creads-video-frame mfp-hide creads-video-creation-47114\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/LEETCHI-POT-DE-DEPART.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1647\" class=\"creads-video-frame mfp-hide creads-video-creation-47093\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/STORY_RECETTE.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1649\" class=\"creads-video-frame mfp-hide creads-video-creation-47093\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/STORY_PROMO.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1659\" class=\"creads-video-frame mfp-hide creads-video-creation-47071\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/LogoSoundlogo.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-802\" class=\"creads-video-frame mfp-hide creads-video-creation-47066\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/DANONE_2_v3.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-804\" class=\"creads-video-frame mfp-hide creads-video-creation-47066\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/DANONE_1_v3.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2755\" class=\"creads-video-frame mfp-hide creads-video-creation-47052\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Logo_Anime_23_SEC.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1294\" class=\"creads-video-frame mfp-hide creads-video-creation-47034\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/01_Pin_Anime.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1296\" class=\"creads-video-frame mfp-hide creads-video-creation-47034\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/02_Pin_Anime.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1339\" class=\"creads-video-frame mfp-hide creads-video-creation-47030\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Renault-VV-DEMO-011020.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-4593\" class=\"creads-video-frame mfp-hide creads-video-creation-47023\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/04\/ALADIN_FOURNISSEURS_h264.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-4595\" class=\"creads-video-frame mfp-hide creads-video-creation-47023\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/04\/ALADIN_GENERIQUE_h264.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-4597\" class=\"creads-video-frame mfp-hide creads-video-creation-47023\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/04\/ALADIN_PREMIUM_h264.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1308\" class=\"creads-video-frame mfp-hide creads-video-creation-46975\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/mango_2-3_01_-V2.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1310\" class=\"creads-video-frame mfp-hide creads-video-creation-46975\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/mango_2-3_02_-V2.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-4360\" class=\"creads-video-frame mfp-hide creads-video-creation-46967\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/03\/ppt-anime\u0301-sncf.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2021\" class=\"creads-video-frame mfp-hide creads-video-creation-46923\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/OSCARO-Billboard-anniversaire.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2023\" class=\"creads-video-frame mfp-hide creads-video-creation-46923\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/OSCARO-Billboard-copie.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2025\" class=\"creads-video-frame mfp-hide creads-video-creation-46923\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/OSCARO-Billboard.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2027\" class=\"creads-video-frame mfp-hide creads-video-creation-46923\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/OSCARO_BILLBOARDS2019_8S_SORTIE_PIECEMECA.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-4219\" class=\"creads-video-frame mfp-hide creads-video-creation-46888\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/03\/Creads-Motion-Design-Showreel.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-726\" class=\"creads-video-frame mfp-hide creads-video-creation-44613\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/01_PETIT_BATEAU.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-728\" class=\"creads-video-frame mfp-hide creads-video-creation-44613\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/02_PETIT_BATEAU.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2899\" class=\"creads-video-frame mfp-hide creads-video-creation-44537\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/BIG-MAT-Voeux-2020.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1761\" class=\"creads-video-frame mfp-hide creads-video-creation-44473\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/VISUEL_CHRONOPOST_V2.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1182\" class=\"creads-video-frame mfp-hide creads-video-creation-44457\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/hellofresh_2_edit.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1184\" class=\"creads-video-frame mfp-hide creads-video-creation-44457\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/hellofresh_4_edit.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1601\" class=\"creads-video-frame mfp-hide creads-video-creation-44455\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Story_recette2_V3.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1603\" class=\"creads-video-frame mfp-hide creads-video-creation-44455\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Story_recetteV4.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1605\" class=\"creads-video-frame mfp-hide creads-video-creation-44455\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Story_rseV5.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2372\" class=\"creads-video-frame mfp-hide creads-video-creation-44447\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/201218-LIMONETIK-KEYVISUAL-VOEUX-17H.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1883\" class=\"creads-video-frame mfp-hide creads-video-creation-44445\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/APCA-Quinzaine-de-la-transmission.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2010\" class=\"creads-video-frame mfp-hide creads-video-creation-44445\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/video-chambdredagriculture-motiondesign.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1771\" class=\"creads-video-frame mfp-hide creads-video-creation-44282\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/OPENTOUR-PARIS-1-DAY.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1763\" class=\"creads-video-frame mfp-hide creads-video-creation-44276\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/ASTRESS.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1755\" class=\"creads-video-frame mfp-hide creads-video-creation-44271\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/open-tour-1080.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1748\" class=\"creads-video-frame mfp-hide creads-video-creation-44269\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/video-wefinup-motiondesign-1.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1746\" class=\"creads-video-frame mfp-hide creads-video-creation-44267\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/WiSEED_rendu_v04.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1371\" class=\"creads-video-frame mfp-hide creads-video-creation-43230\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Pins_Anime_Caudalie_01.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-1322\" class=\"creads-video-frame mfp-hide creads-video-creation-43226\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Poulpeo_04.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-938\" class=\"creads-video-frame mfp-hide creads-video-creation-43198\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/DASH_1-v9.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-940\" class=\"creads-video-frame mfp-hide creads-video-creation-43198\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/DASH_TOTTI_v6.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2918\" class=\"creads-video-frame mfp-hide creads-video-creation-43188\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Audika_V6-1.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-675\" class=\"creads-video-frame mfp-hide creads-video-creation-43143\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/ROUJE-2_v2.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-679\" class=\"creads-video-frame mfp-hide creads-video-creation-43143\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/ROUJE-1_v3-1.mp4\" type=\"video\/mp4\" \/><\/video><\/div><div id=\"creation-video-2577\" class=\"creads-video-frame mfp-hide creads-video-creation-42326\"><video crossorigin=\"anonymous\" preload=\"none\" oncontextmenu=\"return false;\" controls><source src=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/Logo_animado_01.mp4\" type=\"video\/mp4\" \/><\/video><\/div><\/section>\n\n\n<section class=\"creads-block creads-hero background-gradient\">\n  <div class=\"background gradient\" data-color-1=\"#ffffff\" data-color-2=\"#e9f3ff\" style=\"background: linear-gradient(180deg, #ffffff 0%, #e9f3ff 100%);\"><\/div>  <div class=\"container black\">\n    <h1 class=\"hero-title title-big\">Con Creads, obtendr\u00e1s lo mejor de la creaci\u00f3n premium en 4 etapas<\/h1><div class=\"steps-container\"><div class=\"step\"><div class=\"number\">1.<\/div><div class=\"line\"><\/div><p class=\"step-title\">Seleccionamos al mejor creativo para tu proyecto <\/p><\/div><div class=\"step\"><div class=\"number\">2.<\/div><div class=\"line\"><\/div><p class=\"step-title\">Controla los costes y los plazos <\/p><\/div><div class=\"step\"><div class=\"number\">3.<\/div><div class=\"line\"><\/div><p class=\"step-title\">Gestionamos tu proyecto juntos con las mejores condiciones <\/p><\/div><div class=\"step\"><div class=\"number\">4.<\/div><div class=\"line\"><\/div><p class=\"step-title\">\u00a1Solo tendr\u00e1s que recibir tu contenido creativo de calidad!<\/p><\/div><\/div>  <\/div>\n  <\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","footnotes":""},"class_list":["post-40109","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inspiraci\u00f3n en el dise\u00f1o: Su pr\u00f3ximo proyecto merece el mejor creativo<\/title>\n<meta name=\"description\" content=\"Insp\u00edrate para tus proyectos digitales, de v\u00eddeo, de impresi\u00f3n, de marca... y descubre algunos de los trabajos de nuestros mejores creativos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.creads.com\/es\/proyecto-diseno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inspiraci\u00f3n en el dise\u00f1o: Su pr\u00f3ximo proyecto merece el mejor creativo\" \/>\n<meta property=\"og:description\" content=\"Insp\u00edrate para tus proyectos digitales, de v\u00eddeo, de impresi\u00f3n, de marca... y descubre algunos de los trabajos de nuestros mejores creativos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.creads.com\/es\/proyecto-diseno\/\" \/>\n<meta property=\"og:site_name\" content=\"CREADS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/creads\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-13T12:36:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/page-realisation.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2754\" \/>\n\t<meta property=\"og:image:height\" content=\"1524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Inspiraci\u00f3n en el dise\u00f1o: Su pr\u00f3ximo proyecto merece el mejor creativo\" \/>\n<meta name=\"twitter:description\" content=\"Insp\u00edrate para tus proyectos digitales, de v\u00eddeo, de impresi\u00f3n, de marca... y descubre algunos de los trabajos de nuestros mejores creativos.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/page-realisation.png\" \/>\n<meta name=\"twitter:site\" content=\"@creads\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.creads.com\/es\/proyecto-diseno\/\",\"url\":\"https:\/\/www.creads.com\/es\/proyecto-diseno\/\",\"name\":\"Inspiraci\u00f3n en el dise\u00f1o: Su pr\u00f3ximo proyecto merece el mejor creativo\",\"isPartOf\":{\"@id\":\"https:\/\/www.creads.com\/#website\"},\"datePublished\":\"2021-01-14T02:06:13+00:00\",\"dateModified\":\"2021-07-13T12:36:39+00:00\",\"description\":\"Insp\u00edrate para tus proyectos digitales, de v\u00eddeo, de impresi\u00f3n, de marca... y descubre algunos de los trabajos de nuestros mejores creativos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.creads.com\/es\/proyecto-diseno\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.creads.com\/es\/proyecto-diseno\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.creads.com\/es\/proyecto-diseno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Creads\",\"item\":\"https:\/\/www.creads.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.creads.com\/#website\",\"url\":\"https:\/\/www.creads.com\/\",\"name\":\"CREADS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.creads.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.creads.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.creads.com\/#organization\",\"name\":\"Creads\",\"url\":\"https:\/\/www.creads.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.creads.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/06\/Logo-Creads-Baseline-Noir.png\",\"contentUrl\":\"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/06\/Logo-Creads-Baseline-Noir.png\",\"width\":6487,\"height\":2611,\"caption\":\"Creads\"},\"image\":{\"@id\":\"https:\/\/www.creads.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/fr-fr.facebook.com\/creads\/\",\"https:\/\/x.com\/creads\",\"https:\/\/www.instagram.com\/creads\/\",\"https:\/\/fr.linkedin.com\/company\/creads\",\"https:\/\/www.pinterest.fr\/agencecreads\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inspiraci\u00f3n en el dise\u00f1o: Su pr\u00f3ximo proyecto merece el mejor creativo","description":"Insp\u00edrate para tus proyectos digitales, de v\u00eddeo, de impresi\u00f3n, de marca... y descubre algunos de los trabajos de nuestros mejores creativos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.creads.com\/es\/proyecto-diseno\/","og_locale":"es_ES","og_type":"article","og_title":"Inspiraci\u00f3n en el dise\u00f1o: Su pr\u00f3ximo proyecto merece el mejor creativo","og_description":"Insp\u00edrate para tus proyectos digitales, de v\u00eddeo, de impresi\u00f3n, de marca... y descubre algunos de los trabajos de nuestros mejores creativos.","og_url":"https:\/\/www.creads.com\/es\/proyecto-diseno\/","og_site_name":"CREADS","article_publisher":"https:\/\/fr-fr.facebook.com\/creads\/","article_modified_time":"2021-07-13T12:36:39+00:00","og_image":[{"width":2754,"height":1524,"url":"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/page-realisation.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Inspiraci\u00f3n en el dise\u00f1o: Su pr\u00f3ximo proyecto merece el mejor creativo","twitter_description":"Insp\u00edrate para tus proyectos digitales, de v\u00eddeo, de impresi\u00f3n, de marca... y descubre algunos de los trabajos de nuestros mejores creativos.","twitter_image":"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/02\/page-realisation.png","twitter_site":"@creads","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.creads.com\/es\/proyecto-diseno\/","url":"https:\/\/www.creads.com\/es\/proyecto-diseno\/","name":"Inspiraci\u00f3n en el dise\u00f1o: Su pr\u00f3ximo proyecto merece el mejor creativo","isPartOf":{"@id":"https:\/\/www.creads.com\/#website"},"datePublished":"2021-01-14T02:06:13+00:00","dateModified":"2021-07-13T12:36:39+00:00","description":"Insp\u00edrate para tus proyectos digitales, de v\u00eddeo, de impresi\u00f3n, de marca... y descubre algunos de los trabajos de nuestros mejores creativos.","breadcrumb":{"@id":"https:\/\/www.creads.com\/es\/proyecto-diseno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.creads.com\/es\/proyecto-diseno\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.creads.com\/es\/proyecto-diseno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Creads","item":"https:\/\/www.creads.com\/es\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes"}]},{"@type":"WebSite","@id":"https:\/\/www.creads.com\/#website","url":"https:\/\/www.creads.com\/","name":"CREADS","description":"","publisher":{"@id":"https:\/\/www.creads.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.creads.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.creads.com\/#organization","name":"Creads","url":"https:\/\/www.creads.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.creads.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/06\/Logo-Creads-Baseline-Noir.png","contentUrl":"https:\/\/www.creads.com\/wp-content\/uploads\/2021\/06\/Logo-Creads-Baseline-Noir.png","width":6487,"height":2611,"caption":"Creads"},"image":{"@id":"https:\/\/www.creads.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/creads\/","https:\/\/x.com\/creads","https:\/\/www.instagram.com\/creads\/","https:\/\/fr.linkedin.com\/company\/creads","https:\/\/www.pinterest.fr\/agencecreads\/"]}]}},"meta_box":{"creads_header_theme":"light"},"_links":{"self":[{"href":"https:\/\/www.creads.com\/es\/wp-json\/wp\/v2\/pages\/40109"}],"collection":[{"href":"https:\/\/www.creads.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.creads.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.creads.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.creads.com\/es\/wp-json\/wp\/v2\/comments?post=40109"}],"version-history":[{"count":3,"href":"https:\/\/www.creads.com\/es\/wp-json\/wp\/v2\/pages\/40109\/revisions"}],"predecessor-version":[{"id":54044,"href":"https:\/\/www.creads.com\/es\/wp-json\/wp\/v2\/pages\/40109\/revisions\/54044"}],"wp:attachment":[{"href":"https:\/\/www.creads.com\/es\/wp-json\/wp\/v2\/media?parent=40109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}